{"id":1254,"date":"2015-12-11T17:38:19","date_gmt":"2015-12-11T17:38:19","guid":{"rendered":"http:\/\/www.uphill.cat\/blog\/?p=1254"},"modified":"2015-12-11T17:38:19","modified_gmt":"2015-12-11T17:38:19","slug":"dependencia-2","status":"publish","type":"post","link":"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/","title":{"rendered":"Dependencia"},"content":{"rendered":"<p class=\"Standard\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 14.0pt;\">GISBERT CALABUIG en 1985, establece que con la palabra dependencia se pretende se\u00f1alar la falta de libertad en la relaci\u00f3n establecida entre el consumidor y la substancia consumida.<\/span><\/p>\n<p class=\"Standard\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 14.0pt;\">En la siguiente edici\u00f3n de este tratado, el profesor Luna define la dependencia en los siguientes t\u00e9rminos:<\/span><\/p>\n<p class=\"Standard\" style=\"text-align: justify; text-justify: inter-ideograph;\">\u00a0<span style=\"font-size: 14.0pt;\">\u201cLa dependencia hacia una sustancia determinada es como la vinculaci\u00f3n metab\u00f3lica o conductual entre su consumo y una persona, de forma que \u00e9sta no puede prescindir de su consumo sin que aparezcan trastornos de conducta y\/o una serie de s\u00edntomas y signos cl\u00ednicos que desaparecen con la administraci\u00f3n de la sustancia en cuesti\u00f3n.<\/span><\/p>\n<p class=\"Standard\" style=\"text-align: justify; text-justify: inter-ideograph;\"><span style=\"font-size: 14.0pt;\">En definitiva sigue haciendo hincapi\u00e9 en la falta de libertad si bien habla de la vinculaci\u00f3n metab\u00f3lica establecida entre la sustancia y el organismo\u201d.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GISBERT CALABUIG en 1985, establece que con la palabra dependencia se pretende se\u00f1alar la falta de libertad en la relaci\u00f3n establecida entre el consumidor y la substancia consumida. En la siguiente edici\u00f3n de este tratado, el profesor Luna define la dependencia en los siguientes t\u00e9rminos: \u00a0\u201cLa dependencia hacia una sustancia determinada es como la vinculaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1252,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","wp_popup_display_lightbox":0,"wp_popup_suppress":"","wp_popup_trigger":"","wp_popup_trigger_amount":0,"wp_popup_disable_on_mobile":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-1254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dependencia - UPHILL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dependencia - UPHILL\" \/>\n<meta property=\"og:description\" content=\"GISBERT CALABUIG en 1985, establece que con la palabra dependencia se pretende se\u00f1alar la falta de libertad en la relaci\u00f3n establecida entre el consumidor y la substancia consumida. En la siguiente edici\u00f3n de este tratado, el profesor Luna define la dependencia en los siguientes t\u00e9rminos: \u00a0\u201cLa dependencia hacia una sustancia determinada es como la vinculaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/\" \/>\n<meta property=\"og:site_name\" content=\"UPHILL\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-11T17:38:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.uphill.cat\/blog\/wp-content\/uploads\/2015\/12\/addiction-550762_640.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"452\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"uphill\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"uphill\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/\"},\"author\":{\"name\":\"uphill\",\"@id\":\"https:\/\/www.uphill.cat\/blog\/#\/schema\/person\/1ecaa2a5fc82186e869734d24763823b\"},\"headline\":\"Dependencia\",\"datePublished\":\"2015-12-11T17:38:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/\"},\"wordCount\":135,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.uphill.cat\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uphill.cat\/blog\/wp-content\/uploads\/2015\/12\/addiction-550762_640.jpg\",\"articleSection\":[\"Blog es\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/\",\"url\":\"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/\",\"name\":\"Dependencia - UPHILL\",\"isPartOf\":{\"@id\":\"https:\/\/www.uphill.cat\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uphill.cat\/blog\/wp-content\/uploads\/2015\/12\/addiction-550762_640.jpg\",\"datePublished\":\"2015-12-11T17:38:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/#primaryimage\",\"url\":\"https:\/\/www.uphill.cat\/blog\/wp-content\/uploads\/2015\/12\/addiction-550762_640.jpg\",\"contentUrl\":\"https:\/\/www.uphill.cat\/blog\/wp-content\/uploads\/2015\/12\/addiction-550762_640.jpg\",\"width\":640,\"height\":452},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.uphill.cat\/blog\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dependencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uphill.cat\/blog\/#website\",\"url\":\"https:\/\/www.uphill.cat\/blog\/\",\"name\":\"UPHILL\",\"description\":\"CENTRE D'ASSESSORAMENT TERAP&Egrave;UTIC\",\"publisher\":{\"@id\":\"https:\/\/www.uphill.cat\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uphill.cat\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.uphill.cat\/blog\/#organization\",\"name\":\"UPHILL\",\"url\":\"https:\/\/www.uphill.cat\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.uphill.cat\/blog\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.uphill.cat\/blog\/wp-content\/uploads\/2014\/05\/UPHILL_logo.png\",\"contentUrl\":\"http:\/\/www.uphill.cat\/blog\/wp-content\/uploads\/2014\/05\/UPHILL_logo.png\",\"width\":164,\"height\":70,\"caption\":\"UPHILL\"},\"image\":{\"@id\":\"https:\/\/www.uphill.cat\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uphill.cat\/blog\/#\/schema\/person\/1ecaa2a5fc82186e869734d24763823b\",\"name\":\"uphill\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.uphill.cat\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c0757fe53e88a4ba7c5f4b85ab3a5b16b68f79341e32c6e41daf8f276b31644f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c0757fe53e88a4ba7c5f4b85ab3a5b16b68f79341e32c6e41daf8f276b31644f?s=96&d=mm&r=g\",\"caption\":\"uphill\"},\"sameAs\":[\"http:\/\/www.uphill.cat\/blog\",\"https:\/\/www.instagram.com\/uphill_girona\/\"],\"url\":\"https:\/\/www.uphill.cat\/blog\/es\/author\/uphill\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dependencia - UPHILL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/","og_locale":"es_ES","og_type":"article","og_title":"Dependencia - UPHILL","og_description":"GISBERT CALABUIG en 1985, establece que con la palabra dependencia se pretende se\u00f1alar la falta de libertad en la relaci\u00f3n establecida entre el consumidor y la substancia consumida. En la siguiente edici\u00f3n de este tratado, el profesor Luna define la dependencia en los siguientes t\u00e9rminos: \u00a0\u201cLa dependencia hacia una sustancia determinada es como la vinculaci\u00f3n [&hellip;]","og_url":"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/","og_site_name":"UPHILL","article_published_time":"2015-12-11T17:38:19+00:00","og_image":[{"width":640,"height":452,"url":"https:\/\/www.uphill.cat\/blog\/wp-content\/uploads\/2015\/12\/addiction-550762_640.jpg","type":"image\/jpeg"}],"author":"uphill","twitter_misc":{"Escrito por":"uphill","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/#article","isPartOf":{"@id":"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/"},"author":{"name":"uphill","@id":"https:\/\/www.uphill.cat\/blog\/#\/schema\/person\/1ecaa2a5fc82186e869734d24763823b"},"headline":"Dependencia","datePublished":"2015-12-11T17:38:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/"},"wordCount":135,"commentCount":0,"publisher":{"@id":"https:\/\/www.uphill.cat\/blog\/#organization"},"image":{"@id":"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uphill.cat\/blog\/wp-content\/uploads\/2015\/12\/addiction-550762_640.jpg","articleSection":["Blog es"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/","url":"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/","name":"Dependencia - UPHILL","isPartOf":{"@id":"https:\/\/www.uphill.cat\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/#primaryimage"},"image":{"@id":"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uphill.cat\/blog\/wp-content\/uploads\/2015\/12\/addiction-550762_640.jpg","datePublished":"2015-12-11T17:38:19+00:00","breadcrumb":{"@id":"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/#primaryimage","url":"https:\/\/www.uphill.cat\/blog\/wp-content\/uploads\/2015\/12\/addiction-550762_640.jpg","contentUrl":"https:\/\/www.uphill.cat\/blog\/wp-content\/uploads\/2015\/12\/addiction-550762_640.jpg","width":640,"height":452},{"@type":"BreadcrumbList","@id":"https:\/\/www.uphill.cat\/blog\/es\/dependencia-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.uphill.cat\/blog\/es\/"},{"@type":"ListItem","position":2,"name":"Dependencia"}]},{"@type":"WebSite","@id":"https:\/\/www.uphill.cat\/blog\/#website","url":"https:\/\/www.uphill.cat\/blog\/","name":"UPHILL","description":"CENTRE D'ASSESSORAMENT TERAP&Egrave;UTIC","publisher":{"@id":"https:\/\/www.uphill.cat\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uphill.cat\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.uphill.cat\/blog\/#organization","name":"UPHILL","url":"https:\/\/www.uphill.cat\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uphill.cat\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/www.uphill.cat\/blog\/wp-content\/uploads\/2014\/05\/UPHILL_logo.png","contentUrl":"http:\/\/www.uphill.cat\/blog\/wp-content\/uploads\/2014\/05\/UPHILL_logo.png","width":164,"height":70,"caption":"UPHILL"},"image":{"@id":"https:\/\/www.uphill.cat\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.uphill.cat\/blog\/#\/schema\/person\/1ecaa2a5fc82186e869734d24763823b","name":"uphill","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uphill.cat\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c0757fe53e88a4ba7c5f4b85ab3a5b16b68f79341e32c6e41daf8f276b31644f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c0757fe53e88a4ba7c5f4b85ab3a5b16b68f79341e32c6e41daf8f276b31644f?s=96&d=mm&r=g","caption":"uphill"},"sameAs":["http:\/\/www.uphill.cat\/blog","https:\/\/www.instagram.com\/uphill_girona\/"],"url":"https:\/\/www.uphill.cat\/blog\/es\/author\/uphill\/"}]}},"_links":{"self":[{"href":"https:\/\/www.uphill.cat\/blog\/es\/wp-json\/wp\/v2\/posts\/1254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uphill.cat\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uphill.cat\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uphill.cat\/blog\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uphill.cat\/blog\/es\/wp-json\/wp\/v2\/comments?post=1254"}],"version-history":[{"count":1,"href":"https:\/\/www.uphill.cat\/blog\/es\/wp-json\/wp\/v2\/posts\/1254\/revisions"}],"predecessor-version":[{"id":1255,"href":"https:\/\/www.uphill.cat\/blog\/es\/wp-json\/wp\/v2\/posts\/1254\/revisions\/1255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uphill.cat\/blog\/es\/wp-json\/wp\/v2\/media\/1252"}],"wp:attachment":[{"href":"https:\/\/www.uphill.cat\/blog\/es\/wp-json\/wp\/v2\/media?parent=1254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uphill.cat\/blog\/es\/wp-json\/wp\/v2\/categories?post=1254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uphill.cat\/blog\/es\/wp-json\/wp\/v2\/tags?post=1254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}